{"id":5977,"date":"2009-11-03T00:03:31","date_gmt":"2009-11-02T23:03:31","guid":{"rendered":"\/blog\/?p=5977"},"modified":"2017-04-16T21:22:16","modified_gmt":"2017-04-16T19:22:16","slug":"die-erste-million-ist-voll-und-schluss-noch-lange-nicht","status":"publish","type":"post","link":"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/","title":{"rendered":"Die erste Million ist voll &#8211; und Schluss noch lange nicht"},"content":{"rendered":"<p>Wahrheiten.org hat nun seit seiner Entstehung im Sommer 2008 den einmillionsten Besucher gez\u00e4hlt. Einzelne Seitenabrufe waren es sogar etliche Millionen. Das ist eine erstaunliche Entwicklung und war gar nicht so geplant.<\/p>\n<p>Offensichtlich gibt es immer mehr Gleichgesinnte, welche sich Dank Internet finden und multiplizieren k\u00f6nnen, die Zahl derartiger Webseiten w\u00e4chst t\u00e4glich.<\/p>\n<p>Eine tolle Bewegung, die sich mehr und mehr ausbreitet. Ist sie \u00fcberhaupt noch aufzuhalten?<\/p>\n<p><!--more--><\/p>\n<p>Danke an alle Besucher, besonders an diejenigen, die Wahrheiten.org weiterempfohlen haben. Danke an die Co-Autoren und deren gro\u00dfartige Artikel. Insbesondere gro\u00dfen Dank an die eigentlichen Helden, n\u00e4mlich Sie als den Leser, der t\u00e4glich oder regelm\u00e4\u00dfig vorbeischaut oder auch nur wenige Male hier gelesen hat.<\/p>\n<p>Auch geht der Dank an die Kritiker, die nat\u00fcrlich den gro\u00dfen &#8222;Fehler&#8220; begehen und negative Werbung betreiben &#8211; doch auch das ist eine Art von Werbung. Und diejenigen Leser der Kritikerseiten, welche so intelligent sind, sich das eigentliche &#8222;\u00dcbel&#8220; Wahrheiten.org einmal selbst anzuschauen, welches woanders verunglimpft wird, diese betreten d\u00fcnnes Eis. Denn wer kann schon verhindern, dass ein bislang nicht selbst denkender Nachplapperer \u00fcber die eine odere andere Information stolpert, die ihn pl\u00f6tzlich zum Nachdenken bringt?<\/p>\n<p>Vielleicht konnte Wahrheiten.org in der Vergangenheit ja sogar ein kleines bisschen etwas bewegen bei einzelnen Menschen, die zuf\u00e4llig oder durch Empfehlung hier gelandet sind. Es ist sch\u00f6n, Gleichgesinnte virtuell versammelt zu sehen und mit zur &#8222;Aufkl\u00e4rungsgemeinde&#8220; zu geh\u00f6ren.<\/p>\n<p>Auch wenn es jede Menge Arbeit ist, die vielen R\u00fcckmeldungen und die rege Beteiligung best\u00e4tigen das Engagement und motivieren immer wieder neu. Bei den Kontakt-R\u00fcckmeldungen \u00fcberwiegen gl\u00fccklicherweise die positiven. Nat\u00fcrlich gibt es auch Drohungen und Angriffe, teilweise unter der G\u00fcrtellinie, manchmal sogar auf infamste Weise. Diese Angriffe waren bisher auch ausnahmslos anonymer Natur. Ich kenne keinen der harten Kritiker oder Verleumder, der sich namentlich zu erkennen gab.<\/p>\n<p>Einigen &#8222;Kollegen&#8220; ergeht es \u00e4hnlich. Die Hetzer und Angreifer sind immer anonym. Entweder haben sie Angst, ebenfalls angegriffen zu werden oder sie wissen genau, dass sie \u00f6ffentlich als L\u00fcgner entlarvt werden k\u00f6nnten &#8211; mit allen Konsequenzen. Vielleicht sind es auch immer dieselben Angsthasen, die nur nicht als Wiederholungst\u00e4ter entlarvt werden wollen?<\/p>\n<p>Schenken wir diesen armseligen Kreaturen am besten keine weitere Aufmerksamkeit, sie werden noch genug damit zu k\u00e4mpfen haben, wenn all die &#8222;Verschw\u00f6rungstheorien&#8220; urpl\u00f6tzlich zur bitteren Realit\u00e4t mutieren werden.<\/p>\n<p>Es gibt schlie\u00dflich genug Themen, f\u00fcr die wir unsere knappe Zeit einsetzen und auf die wir unsere Aufmerksamkeit besser lenken sollten. Vielen scheint es dabei so zu gehen, dass der Eindruck entsteht, das Karussel dreht sich immer schneller und bunter. Man kommt inzwischen gar nicht mehr hinterher, all die Informationen zu sichten, die den L\u00fcgenmedien entgegengesetzt werden.<\/p>\n<p>Aufkl\u00e4rungsseiten sprie\u00dfen wie &#8222;Unkraut&#8220; aus allen Fugen des Internets. Wohl deswegen hat inzwischen die Politik weltweit das Internet aufs Korn genommen &#8211; f\u00fchlt sich da jemand durch die Wahrheit bedroht?<\/p>\n<p>Regelm\u00e4\u00dfig kommt die Idee, die Aufkl\u00e4rer sollten sich alle zusammenschlie\u00dfen, um wirklich schlagkr\u00e4ftig zu werden und um Aufmerksamkeit erregen zu k\u00f6nnen. Das klingt zun\u00e4chst zwar sinnvoll, jedoch ist so ein Zusammenschluss schwer zu realisieren, weil die Meinungen teilweise sehr weit differieren.<\/p>\n<p>Gel\u00e4nge ein Zusammenschluss, w\u00fcrden Entscheidungswege l\u00e4nger, die Informationen gleichgezogen, die Vielfalt geringer und die interne Politik gr\u00f6\u00dfer. Die gr\u00f6\u00dfte Gefahr birgt aber die potenzielle Unterwanderung. Irgendwer muss und will den Laden am Ende leiten und lenken und dort platziert der Gegner dann geschickt seine Leute &#8211; Peng, Aufkl\u00e4rungsballon geplatzt.<\/p>\n<p>Gerade die Vielfalt, dass jeder selbstdenkende Mensch auf seine spezielle Weise andere Menschen informieren kann, ist der Schl\u00fcssel. Man erreicht mit einem bestimmten Thema und einer bestimmten Darstellungsart niemals alle Menschen gleicherma\u00dfen. Doch durch die gro\u00dfe Unterschiedlichkeit der Aufgekl\u00e4rten wird das Problem perfekt gel\u00f6st.<\/p>\n<p>Nicht jeder muss dazu ins Internet gehen. Informationen von Angesicht zu Angesicht haben einen hohen Stellenwert und gleicherma\u00dfen Glaubw\u00fcrdigkeit. Der Multiplikationseffekt ist jedoch auf elektronischem Wege sehr viel h\u00f6her und kostet dabei sehr viel weniger Zeit und auch Geld.<\/p>\n<p>\u00dcbrigens, wenn Sie gerne schreiben und auch ein gewisses H\u00e4ndchen daf\u00fcr haben, wenn Sie keine Zeit, Lust oder zu wenig Kenntnisse f\u00fcr eine eigene Website haben, wenn Ihnen die auf Wahrheiten.org angesprochenen Themen zusagen oder Sie auch in anderen Themengebieten kompetent sind, dann k\u00f6nnen Sie gerne <a href=\"\/blog\/die-groessten-luegen-der-welt\/kontakt\/\">Kontakt<\/a> aufnehmen. Ver\u00f6ffentlichungen m\u00fcssen nicht mit Ihrem Namen versehen sein, haben aber nat\u00fcrlich eine h\u00f6here Glaubw\u00fcrdigkeit, wenn die Leser eine bestimmte Person genannt bekommen.<\/p>\n<p>Eigentlich m\u00fcsste jeder Aufgekl\u00e4rte zum Aktivisten werden. Aber viele haben Angst, ihren guten Ruf zu verlieren. Immerhin ist das Internet unglaublich transparent. Gerade potenzielle neue Arbeitgeber informieren sich \u00fcber Bewerber auch im Internet. Wird dabei nun die \u00f6ffentliche kritische Meinungs\u00e4u\u00dferung entdeckt, k\u00f6nnte das dem einen oder anderen Chef ein Dorn im Auge sein &#8211; oder umgekehrt. Es soll auch F\u00fchrungskr\u00e4fte geben, die mutige und engagierte Menschen suchen. Lassen Sie sich also nicht immer von Angst leiten, Angst ist ein schlechter Berater.<\/p>\n<p>Wie geht es weiter mit den Wahrheiten? Das ist schwer planbar und in die Zukunft zu schauen ist nur <a href=\"\/blog\/die-groessten-luegen-der-welt\/countdown-zum-finale-der-welt\/\">bedingt m\u00f6glich<\/a>. Sicherlich wird in Zukunft das Thema Zensur sehr ernst werden. Auch Zwangma\u00dfnahmen wie eine Schweinerei-Impfung oder tats\u00e4chlich Unruhen in der Bev\u00f6lkerung, k\u00f6nnen die Lage insgesamt schlagartig ver\u00e4ndern.<\/p>\n<p>Anstatt sich nur von au\u00dfen gezwungenerma\u00dfen ver\u00e4ndern zu lassen, kann jeder selbst etwas zur Ver\u00e4nderung in unserem Sinne beitragen, das muss man nicht einzelnen Web-Autoren \u00fcberlassen. Niemand ist so unwichtig oder unf\u00e4hig, dass er nicht wenigstens eine Kleinigkeit bewirken kann. Schon wer damit beginnt, laut Fragen zu stellen &#8211; Fragen, die sich der Normalb\u00fcrger nicht traut oder eben nicht einmal erkennt &#8211; kann damit unter Umst\u00e4nden viel mehr bewegen, als er es ahnt. Eine weitere einfache M\u00f6glichkeit ist das Verbreiten von Informationen durch <a href=\"\/blog\/klimaluege\/bestellformular-fur-klima-flyer\/\">Flugbl\u00e4tter<\/a>.<\/p>\n<p>Nur Mut. Wer aufgibt, bevor er \u00fcberhaupt begonnen hat, selbst etwas zu unternehmen, der hat sich schon l\u00e4ngst abgeschrieben. Wollen Sie sich f\u00fcgen in Ihr &#8211; von anderen geplantes &#8211; Schicksal?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wahrheiten.org hat nun seit seiner Entstehung im Sommer 2008 den einmillionsten Besucher gez\u00e4hlt. Einzelne Seitenabrufe waren es sogar etliche Millionen. Das ist eine erstaunliche Entwicklung und war gar nicht so geplant. Offensichtlich gibt es immer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6239,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[644],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die erste Million ist voll - und Schluss noch lange nicht | Wahrheiten.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die erste Million ist voll - und Schluss noch lange nicht | Wahrheiten.org\" \/>\n<meta property=\"og:description\" content=\"Wahrheiten.org hat nun seit seiner Entstehung im Sommer 2008 den einmillionsten Besucher gez\u00e4hlt. Einzelne Seitenabrufe waren es sogar etliche Millionen. Das ist eine erstaunliche Entwicklung und war gar nicht so geplant. Offensichtlich gibt es immer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Wahrheiten.org\" \/>\n<meta property=\"article:published_time\" content=\"2009-11-02T23:03:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-16T19:22:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2009\/10\/sekt-flasche.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"251\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wahrheiten.org\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wahrheiten.org\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/\",\"name\":\"Die erste Million ist voll - und Schluss noch lange nicht | Wahrheiten.org\",\"isPartOf\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#website\"},\"datePublished\":\"2009-11-02T23:03:31+00:00\",\"dateModified\":\"2017-04-16T19:22:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.wahrheiten.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die erste Million ist voll &#8211; und Schluss noch lange nicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#website\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\/\",\"name\":\"Wahrheiten.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wahrheiten.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1\",\"name\":\"Wahrheiten.org\",\"sameAs\":[\"http:\/\/www.wahrheiten.org\"],\"url\":\"https:\/\/www.wahrheiten.org\/blog\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die erste Million ist voll - und Schluss noch lange nicht | Wahrheiten.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/","og_locale":"de_DE","og_type":"article","og_title":"Die erste Million ist voll - und Schluss noch lange nicht | Wahrheiten.org","og_description":"Wahrheiten.org hat nun seit seiner Entstehung im Sommer 2008 den einmillionsten Besucher gez\u00e4hlt. Einzelne Seitenabrufe waren es sogar etliche Millionen. Das ist eine erstaunliche Entwicklung und war gar nicht so geplant. Offensichtlich gibt es immer [&hellip;]","og_url":"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/","og_site_name":"Wahrheiten.org","article_published_time":"2009-11-02T23:03:31+00:00","article_modified_time":"2017-04-16T19:22:16+00:00","og_image":[{"width":"251","height":"400","url":"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2009\/10\/sekt-flasche.jpg","type":"image\/jpeg"}],"author":"Wahrheiten.org","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Wahrheiten.org","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/","url":"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/","name":"Die erste Million ist voll - und Schluss noch lange nicht | Wahrheiten.org","isPartOf":{"@id":"https:\/\/www.wahrheiten.org\/blog\/#website"},"datePublished":"2009-11-02T23:03:31+00:00","dateModified":"2017-04-16T19:22:16+00:00","author":{"@id":"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1"},"breadcrumb":{"@id":"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wahrheiten.org\/blog\/2009\/11\/03\/die-erste-million-ist-voll-und-schluss-noch-lange-nicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.wahrheiten.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Die erste Million ist voll &#8211; und Schluss noch lange nicht"}]},{"@type":"WebSite","@id":"https:\/\/www.wahrheiten.org\/blog\/#website","url":"https:\/\/www.wahrheiten.org\/blog\/","name":"Wahrheiten.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wahrheiten.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1","name":"Wahrheiten.org","sameAs":["http:\/\/www.wahrheiten.org"],"url":"https:\/\/www.wahrheiten.org\/blog"}]}},"_links":{"self":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts\/5977"}],"collection":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/comments?post=5977"}],"version-history":[{"count":0,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts\/5977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/media\/6239"}],"wp:attachment":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/media?parent=5977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/categories?post=5977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/tags?post=5977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}