{"id":5398,"date":"2009-09-02T00:03:13","date_gmt":"2009-09-01T22:03:13","guid":{"rendered":"\/blog\/?p=5398"},"modified":"2017-04-16T21:22:18","modified_gmt":"2017-04-16T19:22:18","slug":"tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu","status":"publish","type":"post","link":"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/","title":{"rendered":"Tamiflu &#8211; die Todesfalle schnappt jetzt richtig zu"},"content":{"rendered":"<p>Da die Schweinereigrippe in der BRD kaum noch ernst genommen wird und die B\u00fcrger sich nur zu einem sehr geringen Teil freiwillig impfen lassen m\u00f6chten, wird nun die n\u00e4chste Propagandastufe gez\u00fcndet.<\/p>\n<p>Es w\u00e4re doch gelacht, wenn die furchtbar tr\u00e4gen Deutschen nicht doch noch durch ein paar gezielte Marketingaktionen hinter dem Ofen hervorgelockt bzw. rausgejagt werden k\u00f6nnten.<!--more--><\/p>\n<p>An der Wortwahl ist ganz offensichtlich zu erkennen, dass die Schweinegrippe eine ganz konkret geplante Ma\u00dfnahme ist. <a href=\"http:\/\/www.welt.de\/die-welt\/politik\/article4425028\/Impfung-gegen-Schweinegrippe-droht-Flop-in-Deutschland.html\">Welt Online<\/a> berichtet dazu am 29.08.2009:<\/p>\n<blockquote><p>Impfung gegen Schweinegrippe droht Flop in Deutschland<\/p>\n<p>Einen gro\u00dfen Ansturm wird es auf die Impfung gegen Schweinegrippe wohl nicht geben. Das erwartet zumindest der Vizepr\u00e4sident der Bundes\u00e4rztekammer, Frank Ulrich Montgomery. &#8222;Die Impfaktion wird kein Renner&#8220;, sagte Montgomery dem &#8222;Focus&#8220;.<\/p><\/blockquote>\n<p>Soso, die Impfung sollte also ein Renner werden. Sprechen so besorgte Menschen oder Mediziner \u00fcber hochgef\u00e4hrliche und vielleicht sogar t\u00f6dliche Gefahren? Sagt man zu einer gescheiterten Rettungsaktion &#8222;Flop&#8220;, bei der es um die Gesundheit und das \u00dcberleben von Millionen, nein, Milliarden von Menschen geht?<\/p>\n<p>&#8222;Flop&#8220; und &#8222;Renner&#8220; sind vollkommen unpassend. Doch selbst wenn in der Zeitung st\u00fcnde &#8222;Pharmaunternehmen m\u00f6chten Milliarden durch Zwangsimpfung verdienen&#8220; &#8211; meinen Sie, das m\u00fcde Volk w\u00fcrde auch nur die Augenlieder heben? Vielleicht k\u00e4me ein m\u00fcdes Zwinkern hervor. Was f\u00fcr eine Pappnasengesellschaft ist das hier eigentlich?<\/p>\n<p>Unsere unf\u00e4higen Mitb\u00fcrger sind so passiv, dass sich laut Bundes\u00e4rztekammer nur sehr wenige \u00fcberhaupt impfen lassen wollen &#8211; Gl\u00fcck im Ungl\u00fcck? Das <a href=\"http:\/\/www.abendblatt.de\/ratgeber\/wissen\/article1161816\/Die-meisten-wollen-keine-Impfung-gegen-Schweinegrippe.html\">Hamburger Abendblatt<\/a> schrieb dazu am 31.08.2009:<\/p>\n<blockquote><p>In der Gesamtbev\u00f6lkerung w\u00fcrden sich nur 15 bis 20 Prozent impfen lassen, bei bestimmten Risikogruppen etwa die H\u00e4lfte, sch\u00e4tzt Montgomery. Laut einer repr\u00e4sentativen Umfrage des Nachrichtenmagazins &#8222;Der Spiegel&#8220; will sich die Mehrheit der Deutschen nicht gegen das neue Grippevirus H1N1 impfen lassen.<\/p><\/blockquote>\n<p>Was k\u00f6nnte die kurz vor der v\u00f6lligen Verarmung stehende Pharmabranche denn nun noch retten? Richtig: Die Zwangsimpfung. Aber wozu Gesetze und Gewalt anwenden, wenn man Zwang auch indirekt aus\u00fcben kann und daf\u00fcr keinerlei zus\u00e4tzliches Personal zur Unterdr\u00fcckung ben\u00f6tigt.<\/p>\n<p>Man macht das viel eleganter: Mit Sch\u00fcren von Panik. Wie <a href=\"\/blog\/2009\/04\/27\/h1n1-startet-jetzt-die-geplante-pandemie\/\">bereits vor Monaten vorausgesagt<\/a> und von Dr. Stefan Lanka <a href=\"\/blog\/2009\/08\/03\/nanotechnik-und-impfstoffe-ein-perfektes-paar\/\">ausf\u00fchrlich erkl\u00e4rt<\/a>, werden nun einzelne Patienten geopfert, um die Masse in Angst und Schrecken zu versetzen. <a href=\"http:\/\/www.bild.de\/BILD\/ratgeber\/gesund-fit\/2009\/09\/01\/schweinegrippe-tamiflu\/relenza-warum-wirken-die-mittel-nicht-bei-jedem-resistenzen.html\">Bild.de<\/a> titelte daher am 01.09.2009:<\/p>\n<blockquote><p>Wirkt Tamiflu bald nicht mehr?<\/p>\n<p>Bisher verliefen die Schweinegrippe-F\u00e4lle in Deutschland alle sehr mild. Doch jetzt k\u00e4mpft ein 35-j\u00e4hriger Infizierter in Bonn um sein Leben. Er wurde mit dem Grippe-Mittel Tamiflu behandelt.<\/p><\/blockquote>\n<p>Der arme Mensch bekam tats\u00e4chlich Tamiflu, was ihn in seiner symptomatischen Situation &#8211; <a href=\"\/blog\/krebsluege\/\">nach der GNM<\/a> sind die &#8222;Grippesymptome&#8220; nichts weiter als die Heilungsphase &#8211; in akute Sauerstoffnot bringt. Er steht kurz vor dem Erstickungstod durch Tamiflu.<\/p>\n<p>Werden sie den jungen Mann tats\u00e4chlich opfern? Ja, sie werden es tun. Und das ist erst der Anfang. Sie werden soviele Menschen \u00f6ffentlich vergiften wie n\u00f6tig sind, um die gew\u00fcnschte Massenimpfung doch noch zu einem &#8222;Renner&#8220; werden zu lassen. In Panik werden die B\u00fcrger die Arztpraxen und Apotheken st\u00fcrmen &#8211; warten Sie es einfach ab.<\/p>\n<p>Sie halten diese Gedanken und Mutma\u00dfungen f\u00fcr v\u00f6llig unsinnig und \u00fcberzogen? Lesen Sie, was <a href=\"http:\/\/www.bild.de\/BILD\/news\/2009\/09\/01\/schweinegrippe-virus-h1n1\/deutscher-in-lebensgefahr-mutiert-virus.html\">Bild.de<\/a> am 01.09.2009 zu diesem konkreten Fall n\u00e4her erkl\u00e4rt:<\/p>\n<blockquote><p>Erster Deutscher (35) in Lebensgefahr<\/p>\n<p>Die Schweinegrippe grassiert weiter: Der erste Patient in Deutschland ringt mit dem Tod! Er hatte sich mit dem gef\u00e4hrlichen Virus infiziert.<\/p>\n<p>[&#8230;]<\/p>\n<p>Der junge Mann wurde letzte Woche station\u00e4r aufgenommen. Das Gegenmittel Tamiflu schlug an, erkl\u00e4rte die Sprecherin gegen\u00fcber BILD.de \u2013 eine Mutation des Virus wird somit also ausgeschlossen. \u201eDer Patient hatte ein Grundrisiko.\u201c<\/p><\/blockquote>\n<p>Richtig, der Patient hatte ein Grundrisiko, er kam n\u00e4mlich in die H\u00e4nde dieser \u00c4rzte und wird nun instrumentalisiert im Dienste der erw\u00fcnschten Panik &#8211; es ist unfassbar.<\/p>\n<p>Wer jetzt immer noch nicht erkannt hat, dass diese propagandistische Virenstory eine einzige f\u00fcrchterliche L\u00fcge ist, der m\u00f6ge sich bitte schon einmal den Arm freimachen &#8211; dem ist wirklich <a href=\"http:\/\/www.youtube.com\/watch?v=mWHw-3E-xXo&amp;eurl=https%3A%2F%2Fwww.wahrheiten.org%2Fblog%2F2009%2F08%2F03%2Fnanotechnik-und-impfstoffe-ein-perfektes-paar%2F&amp;feature=player_embedded\">nicht mehr zu helfen<\/a>.<\/p>\n<p>Wie sonst kann schon Monate vorher bekannt sein, welche Folgen auftreten, welche wahrscheinlichen Mutationen passieren und welche Gegenma\u00dfnahmen helfen werden? Es ist mehr als offensichtlich, was hier gespielt wird. Ein Mordkomplott gegen ganze V\u00f6lker ist das!<\/p>\n<p>Kl\u00e4ren Sie Ihre Mitmenschen auf, zeigen Sie die Vortr\u00e4ge zum Thema, verweisen Sie auf Berichte von vor Monaten und gehen Sie nicht mehr auf diese L\u00fcgen ein, die in den Medien brav heruntergebetet werden. Lassen Sie sich unter keinen Umst\u00e4nden impfen oder Tamiflu verpassen, sondern im Gegenteil, fragen Sie \u00c4rzte und Beh\u00f6rden nach dem offiziellen Nachweis des Schweinegrippe-Erregers.<\/p>\n<p>Wann ist endlich Schluss mit dieser Perversion?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da die Schweinereigrippe in der BRD kaum noch ernst genommen wird und die B\u00fcrger sich nur zu einem sehr geringen Teil freiwillig impfen lassen m\u00f6chten, wird nun die n\u00e4chste Propagandastufe gez\u00fcndet. Es w\u00e4re doch gelacht, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5408,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tamiflu - die Todesfalle schnappt jetzt richtig zu | Wahrheiten.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tamiflu - die Todesfalle schnappt jetzt richtig zu | Wahrheiten.org\" \/>\n<meta property=\"og:description\" content=\"Da die Schweinereigrippe in der BRD kaum noch ernst genommen wird und die B\u00fcrger sich nur zu einem sehr geringen Teil freiwillig impfen lassen m\u00f6chten, wird nun die n\u00e4chste Propagandastufe gez\u00fcndet. Es w\u00e4re doch gelacht, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/\" \/>\n<meta property=\"og:site_name\" content=\"Wahrheiten.org\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-01T22:03:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-16T19:22:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2009\/09\/pillen_772_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wahrheiten.org\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wahrheiten.org\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/\",\"name\":\"Tamiflu - die Todesfalle schnappt jetzt richtig zu | Wahrheiten.org\",\"isPartOf\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#website\"},\"datePublished\":\"2009-09-01T22:03:13+00:00\",\"dateModified\":\"2017-04-16T19:22:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.wahrheiten.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tamiflu &#8211; die Todesfalle schnappt jetzt richtig zu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#website\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\/\",\"name\":\"Wahrheiten.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wahrheiten.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1\",\"name\":\"Wahrheiten.org\",\"sameAs\":[\"http:\/\/www.wahrheiten.org\"],\"url\":\"https:\/\/www.wahrheiten.org\/blog\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tamiflu - die Todesfalle schnappt jetzt richtig zu | Wahrheiten.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/","og_locale":"de_DE","og_type":"article","og_title":"Tamiflu - die Todesfalle schnappt jetzt richtig zu | Wahrheiten.org","og_description":"Da die Schweinereigrippe in der BRD kaum noch ernst genommen wird und die B\u00fcrger sich nur zu einem sehr geringen Teil freiwillig impfen lassen m\u00f6chten, wird nun die n\u00e4chste Propagandastufe gez\u00fcndet. Es w\u00e4re doch gelacht, [&hellip;]","og_url":"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/","og_site_name":"Wahrheiten.org","article_published_time":"2009-09-01T22:03:13+00:00","article_modified_time":"2017-04-16T19:22:18+00:00","og_image":[{"width":"400","height":"300","url":"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2009\/09\/pillen_772_2.jpg","type":"image\/jpeg"}],"author":"Wahrheiten.org","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Wahrheiten.org","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/","url":"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/","name":"Tamiflu - die Todesfalle schnappt jetzt richtig zu | Wahrheiten.org","isPartOf":{"@id":"https:\/\/www.wahrheiten.org\/blog\/#website"},"datePublished":"2009-09-01T22:03:13+00:00","dateModified":"2017-04-16T19:22:18+00:00","author":{"@id":"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1"},"breadcrumb":{"@id":"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wahrheiten.org\/blog\/2009\/09\/02\/tamiflu-die-todesfalle-schnappt-jetzt-richtig-zu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.wahrheiten.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Tamiflu &#8211; die Todesfalle schnappt jetzt richtig zu"}]},{"@type":"WebSite","@id":"https:\/\/www.wahrheiten.org\/blog\/#website","url":"https:\/\/www.wahrheiten.org\/blog\/","name":"Wahrheiten.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wahrheiten.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1","name":"Wahrheiten.org","sameAs":["http:\/\/www.wahrheiten.org"],"url":"https:\/\/www.wahrheiten.org\/blog"}]}},"_links":{"self":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts\/5398"}],"collection":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/comments?post=5398"}],"version-history":[{"count":0,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts\/5398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/media\/5408"}],"wp:attachment":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/media?parent=5398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/categories?post=5398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/tags?post=5398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}