{"id":31757,"date":"2017-03-29T00:05:26","date_gmt":"2017-03-28T22:05:26","guid":{"rendered":"http:\/\/www.wahrheiten.org\/blog\/?p=31757"},"modified":"2017-04-16T20:50:44","modified_gmt":"2017-04-16T18:50:44","slug":"klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete","status":"publish","type":"post","link":"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/","title":{"rendered":"Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte"},"content":{"rendered":"<p>Der Fr\u00fchling beginnt, wenn die Forsythie bl\u00fcht, sagt der Deutsche Wetterdienst. Dabei dient ihm ein Strauch an der Lombardsbr\u00fccke inmitten von Hamburg als Referenz.<\/p>\n<p>Nat\u00fcrlich, so behaupten die gleichgeschalteten Medien, beginne der Bl\u00fchtermin immer fr\u00fcher. Bei der Untersuchung dieser gewagten These und der Analyse der tats\u00e4chlichen Bl\u00fchtermine der Forsythie \u00fcber die letzten 30 Jahre offenbarte sich Erstaunliches.<!--more-->In diesem Jahr bl\u00fchen in Deutschland die Forsythien, die auch Goldflieder oder Goldgl\u00f6ckchen genannt werden, erst seit dem 20. M\u00e4rz. Durch ihre fast \u00fcberall gleichzeitige Bl\u00fchte und ihr dominantes, eindr\u00fcckliches Erscheinungsbild, stechen die gelben Stangenbl\u00fcter besonders ins Auge und deuten zweifellos auf den beginnenden Fr\u00fchling hin.<\/p>\n<p>Aber bl\u00fchen sie tats\u00e4chlich immer fr\u00fcher? Was sagen die Fakten dazu? Vor allem Laien und Medienvertreter m\u00f6gen bitte zun\u00e4chst beachten, dass <a href=\"\/blog\/wp-content\/uploads\/2017\/03\/2-1.jpg\">in dieser Grafik auf der x-Achse die Bl\u00fchtermine der Forsythie<\/a> als Anzahl der Tage nach Neujahr\u00a0gerechnet aufgetragen sind. Ein Ansteigen der Verlaufs- und Trendlinie weist somit auf einen sp\u00e4ten Bl\u00fchtermin hin und nicht etwa auf eine angeblich steigende Temperatur bzw. &#8222;Klimaerw\u00e4rmung&#8220;.<\/p>\n<p>Aus diesen Daten l\u00e4sst sich unmittelbar eine sehr interessante Tatsache herauslesen: Vor 30 Jahren begannen die Forsythien noch im Februar zu bl\u00fchen &#8211; 50 Tage entsprechen in der Grafik dem 19. Februar. In diesem Jahr hingegen startete die beeindruckende Bl\u00fctenpracht einen ganzen Monat sp\u00e4ter &#8211; genauer gesagt 83 Tage nach Jahresbeginn &#8211; und weist insgesamt un\u00fcbersehbar einen sp\u00e4teren Trend auf.<\/p>\n<p>Die \u00dcberraschung \u00fcber diese Erkenntnis ist sicherlich gro\u00df, da die meisten aufgrund der allgegenw\u00e4rtigen CO2-Propaganda sicherlich zun\u00e4chst das Gegenteil vermuten w\u00fcrden. Die Hamburger Daten zeigen also eine Versp\u00e4tung seit 1988 und nicht etwa die stets in allen Medien behauptete immer fr\u00fchere Bl\u00fcte. K\u00f6nnen die meist nicht naturwissenschaftlich ausgebildeten Journalisten der Massenmedien die Diagramme einfach nicht lesen oder handelt es sich bei ihrer Realit\u00e4tsverweigerung schlicht um ideologische Verblendung?<\/p>\n<p>Wir stellen nun fest: Obwohl die Beobachtungsreihe mitten in der gro\u00dfen W\u00e4rmeinsel Hamburg erfasst wurde und damit gar nicht die Bedingungen einer objektiven Beobachtung in der freien Natur erf\u00fcllt, ist der Bl\u00fctebeginn des Forsythien-Vergleichsstrauchs des Deutschen Wetterdiensts seit 30 Jahren eindeutig versp\u00e4tet. Der Fr\u00fchling erwachte in Deutschland innerhalb der letzten 30 Jahre kontinuierlich sp\u00e4ter und nicht wie behauptet immer fr\u00fcher.<\/p>\n<p>Wegen des innerhalb dieses Zeitraums zweifellos gestiegenen CO2-Gehalts der Luft h\u00e4tten die Forsythien eigentlich Jahr f\u00fcr Jahr fr\u00fcher bl\u00fchen m\u00fcssen, und zwar nicht nur wegen das angeblichen Zusammenhangs zwischen dem <a href=\"https:\/\/www.wahrheiten.org\/blog\/klimaluege\/bestellformular-fur-klima-flyer\/\">Spurengas<\/a> und dem Klima, sondern auch weil Kohlendioxid f\u00fcr die Pflanzen ein elementares D\u00fcngemittel darstellt. Doch weshalb geschah hier nicht das Behauptete?<\/p>\n<p>Ganz einfach: Die Temperaturen bestimmen den Bl\u00fctebeginn, nicht der Kohlendioxidgehalt der Atemluft. Da <a href=\"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/08\/langfristiger-abkuehlungstrend-haelt-an-wintermonate-trotz-klimaerwaermung-immer-kaelter\/\">die Winter in Deutschland und in anderen L\u00e4ndern in den letzten 30 Jahren jedoch stetig k\u00e4lter<\/a> ausfielen, kommt der Fr\u00fchling eben notwendigerweise gleicherma\u00dfen erst deutlich sp\u00e4ter in die G\u00e4nge.<\/p>\n<p>Das Fazit dieser Beobachtung: Obwohl die CO2-Konzentration der Atmosph\u00e4re in den vergangenen 30 Jahren gestiegen ist, wurden die Winter k\u00e4lter und die Forsythien bl\u00fchen sp\u00e4ter. Von einer menschengemachten &#8222;<a href=\"http:\/\/klima.wahrheiten.org\">Klimaerw\u00e4rmung<\/a>&#8220; fehlt also weiterhin jede Spur &#8211; zumindest in der Natur, in den Medien und der Politik ist diese Propaganda leider allgegenw\u00e4rtig.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Fr\u00fchling beginnt, wenn die Forsythie bl\u00fcht, sagt der Deutsche Wetterdienst. Dabei dient ihm ein Strauch an der Lombardsbr\u00fccke inmitten von Hamburg als Referenz. Nat\u00fcrlich, so behaupten die gleichgeschalteten Medien, beginne der Bl\u00fchtermin immer fr\u00fcher. [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":31759,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte | Wahrheiten.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte | Wahrheiten.org\" \/>\n<meta property=\"og:description\" content=\"Der Fr\u00fchling beginnt, wenn die Forsythie bl\u00fcht, sagt der Deutsche Wetterdienst. Dabei dient ihm ein Strauch an der Lombardsbr\u00fccke inmitten von Hamburg als Referenz. Nat\u00fcrlich, so behaupten die gleichgeschalteten Medien, beginne der Bl\u00fchtermin immer fr\u00fcher. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/\" \/>\n<meta property=\"og:site_name\" content=\"Wahrheiten.org\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-28T22:05:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-16T18:50:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2017\/03\/1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"693\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Josef Kowatsch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Josef Kowatsch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/\",\"name\":\"Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte | Wahrheiten.org\",\"isPartOf\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#website\"},\"datePublished\":\"2017-03-28T22:05:26+00:00\",\"dateModified\":\"2017-04-16T18:50:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/d1404b38b1bf064051bfa9f275af3d05\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.wahrheiten.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#website\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\/\",\"name\":\"Wahrheiten.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wahrheiten.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/d1404b38b1bf064051bfa9f275af3d05\",\"name\":\"Josef Kowatsch\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte | Wahrheiten.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/","og_locale":"de_DE","og_type":"article","og_title":"Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte | Wahrheiten.org","og_description":"Der Fr\u00fchling beginnt, wenn die Forsythie bl\u00fcht, sagt der Deutsche Wetterdienst. Dabei dient ihm ein Strauch an der Lombardsbr\u00fccke inmitten von Hamburg als Referenz. Nat\u00fcrlich, so behaupten die gleichgeschalteten Medien, beginne der Bl\u00fchtermin immer fr\u00fcher. [&hellip;]","og_url":"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/","og_site_name":"Wahrheiten.org","article_published_time":"2017-03-28T22:05:26+00:00","article_modified_time":"2017-04-16T18:50:44+00:00","og_image":[{"width":693,"height":576,"url":"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2017\/03\/1-1.jpg","type":"image\/jpeg"}],"author":"Josef Kowatsch","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Josef Kowatsch","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/","url":"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/","name":"Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte | Wahrheiten.org","isPartOf":{"@id":"https:\/\/www.wahrheiten.org\/blog\/#website"},"datePublished":"2017-03-28T22:05:26+00:00","dateModified":"2017-04-16T18:50:44+00:00","author":{"@id":"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/d1404b38b1bf064051bfa9f275af3d05"},"breadcrumb":{"@id":"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wahrheiten.org\/blog\/2017\/03\/29\/klimaerwaermung-der-fruehling-erwacht-spaeter-seit-30-jahren-verzoegert-sich-die-forsythienbluete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.wahrheiten.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Klimaerw\u00e4rmung? Der Fr\u00fchling erwacht sp\u00e4ter: Seit 30 Jahren verz\u00f6gert sich die Forsythienbl\u00fcte"}]},{"@type":"WebSite","@id":"https:\/\/www.wahrheiten.org\/blog\/#website","url":"https:\/\/www.wahrheiten.org\/blog\/","name":"Wahrheiten.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wahrheiten.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/d1404b38b1bf064051bfa9f275af3d05","name":"Josef Kowatsch","url":"https:\/\/www.wahrheiten.org\/blog"}]}},"_links":{"self":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts\/31757"}],"collection":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/comments?post=31757"}],"version-history":[{"count":0,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts\/31757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/media\/31759"}],"wp:attachment":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/media?parent=31757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/categories?post=31757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/tags?post=31757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}