{"id":20875,"date":"2011-07-05T00:03:30","date_gmt":"2011-07-04T22:03:30","guid":{"rendered":"http:\/\/www.wahrheiten.org\/blog\/?p=20875"},"modified":"2017-04-16T21:07:21","modified_gmt":"2017-04-16T19:07:21","slug":"verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering","status":"publish","type":"post","link":"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/","title":{"rendered":"Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering"},"content":{"rendered":"<p>Uns droht demn\u00e4chst der Klimakollaps und anschlie\u00dfend eine von politischen Extremismen und Instabilit\u00e4ten gepr\u00e4gte Welt. Damit sch\u00fcren prominente Politiker nach wie vor Panik in Sachen Klima-L\u00fcge.<\/p>\n<p>In Anbetracht des langsam beginnenden Klimafaschismus wirken die haarstr\u00e4ubenden Pl\u00e4ne und Ideen zur Klimarettung geradezu l\u00e4cherlich und stellen eine gemeine Beleidigung f\u00fcr den Verstand der gesamten Menschheit dar. Wer ist wohl kr\u00e4nker, unser Klima oder die Politik?<!--more-->Zum Grillen ist gutes Wetter wichtig, sonst macht die sch\u00f6nste Grillparty keinen Spa\u00df. \u00c4hnlich sieht es auch die Politik in Sachen Neuer Weltordnung, denn die Spa\u00dfbremse ist dort offenbar die fehlende Unterw\u00fcrfigkeit unter die CO2-Sekte. Diktatur mit Widerworten macht einfach keine Laune. Einer unserer obersten Klimapatriarchen \u00e4u\u00dferte sich dazu mit folgenden Wortlaut, wie ihn der <a href=\"http:\/\/www.stern.de\/news2\/aktuell\/roettgen-warnt-vor-scheitern-der-internationalen-klimagespraeche-1701767.html\">Stern<\/a> am 02.07.2011 zitierte:<\/p>\n<blockquote><p>Ohne wirksamen Klimaschutz sei eine stabile Weltordnung nicht mehr denkbar, schrieb R\u00f6ttgen [&#8230;].<\/p><\/blockquote>\n<p>Wenn es der Menschheit nicht gel\u00e4nge, den Klimawandel in den Griff zu bekommen, dann w\u00fcrde sie durch Hunger und Armut v\u00f6llig zerr\u00fcttet werden. Darauf ist nur zu entgegnen: Wenn es der Politik nicht endlich gelingt, den L\u00fcgen und Betr\u00fcgereien vollst\u00e4ndig Einhalt zu gebieten, dann werden diese Marionetten zweifelsfrei am Ende daf\u00fcr zur Rechenschaft gezogen werden.<\/p>\n<p>Von unserer Parteienlandschaft brauchen wir freilich keine Hilfe zu erwarten, denn diese kl\u00e4ren die <a title=\"Die Klima-L\u00fcge\" href=\"\/blog\/klimaluege\/\">Klima-L\u00fcge<\/a> schlie\u00dflich keineswegs auf, sondern stecken in Wahrheit sogar als Helfershelfer mit den Drahtziehern unter einer Decke. Die neue KPD, die Klima-Partei Deutschlands, besteht aus den klimafreundlichen sozialistischen Parteien CDU, CSU, FDP, SPD, Gr\u00fcne und Linke. Eher wird uns dieser faschistische Laden noch das Atmen verbieten, bevor er sich gegen die L\u00fcgen erhebt.<\/p>\n<p>Eine, die es als Physikerin eigentlich besser wissen m\u00fcsste, ist die alternativlose Abkanzlerin Angela Merkel. Auf dem Petersberger Klimadialog in Berlin sprach sie von zu wenig Ma\u00dfnahmen, so die <a href=\"http:\/\/www.tagesschau.de\/inland\/petersbergerklima102.html\">Tagesschau<\/a> am 03.07.2011:<\/p>\n<blockquote><p>Die freiwilligen CO2-Minderungsziele seien zu wenig, sagte Merkel weiter. Die klimasch\u00e4dlichen Emissionen entwickelten sich weiter sehr besorgniserregend. Extreme Wetterereignisse und steigende Meeresspiegel deuteten auf Ph\u00e4nomene hin, die man sehr ernst nehmen m\u00fcsse.<\/p><\/blockquote>\n<p>Wie Recht sie doch hat. W\u00e4hrend wir uns in Sicherheit wiegen, spielt das Wetter immer mehr verr\u00fcckt: Im Fr\u00fchling ist es inzwischen meist fr\u00fchlingshaft, im Sommer sommerlich, der Herbst wartet zunehmend mit herbstlicher Witterung auf und der Winter zeigt sich immer mehr in \u00fcbelst winterlicher Art und Weise. Wenn das mal kein gef\u00e4hrliches Ph\u00e4nomen ist.<\/p>\n<p>Gar nicht zu reden vom steigenden Meeresspiegel. Dass sich der gleichnamige gro\u00dfe Verlag aus Hamburg vorsorglich in einem <a href=\"http:\/\/www.szene-in-hamburg.de\/bildergallery\/albums\/userpics\/10001\/spiegel.jpg\">Hochhaus<\/a> vor den angeblich steigenden Wassermassen verschanzt hat, zeigt nur, wie ernst es dem <a href=\"http:\/\/www.spiegel.de\/wissenschaft\/natur\/0,1518,771386,00.html\">Spiegel<\/a> mit dem Thema ist. Fast t\u00e4glich ist das dortige Klima-L\u00fcgenradio auf Sendung, so auch am 29.06.2011 erst wieder:<\/p>\n<blockquote><p>Die Erdatmosph\u00e4re erw\u00e4rmt sich immer weiter, der Aussto\u00df von Treibhausgasen steigt und steigt. [&#8230;] Seit mehr als 25 Jahren liege die globale Temperatur jeden Monat \u00fcber dem jeweils gemessenen Durchschnittswert im 20. Jahrhundert [&#8230;].<\/p><\/blockquote>\n<p>Die Industrialisierung begann demnach also erst vor 25 Jahren? Das m\u00fcsste definitiv der Fall sein, wenn es einen echten Zusammenhang zwischen einer angeblichen Klimaerw\u00e4rmung und dem vermehrten Aussto\u00df von &#8222;Treibhausgasen&#8220; g\u00e4be. Wie passt es eigentlich ins Bild, dass in den Siebzigern die meisten Kernkraftwerke zur Stromerzeugung gebaut wurden, die nachweislich gar kein CO2 freisetzen?<\/p>\n<p>K\u00f6nnen Sie sich denn selbst noch vage an die Zeit vor 1985 erinnern? Richtig, das war die Zeit der Pferdekutschen, der fehlenden Stromversorgung und einem Anteil von 95% Bauern in der gesamten Nation. Damals war es deutlich k\u00e4lter und unsere Eltern froren selbst noch im Hochsommer in ihren Iglus im Rheintal.<\/p>\n<p>Wie einfach und schlussendlich aussagelos es ist, zwei beliebige Statistiken in einen vermeintlichen Zusammenhang zu bringen, zeigt das folgende Beispiel. Die <a href=\"http:\/\/www.ifb.bayern.de\/imperia\/md\/images\/stmas\/ifb\/system\/famreport2009_chart1.jpg\">Anteile nichtehelicher Lebendgeburten<\/a> in Bayern und der EU stiegen seit 1990 deutlich an, wie das <a href=\"http:\/\/www.ifb.bayern.de\/forschung\/akt_familienreport.html\">Staatsinstitut f\u00fcr Familienforschung<\/a> an der Universit\u00e4t Bamberg ver\u00f6ffentlichte.<\/p>\n<p>Der <a href=\"http:\/\/www.lbv.de\/typo3temp\/pics\/52e83c8803.jpg\">Wei\u00dfstorch-Bestand in Bayern<\/a> wird vom <a href=\"http:\/\/www.lbv.de\/artenschutz\/voegel\/weissstorch\/bestand-und-gefaehrdung.html\">Landesbund f\u00fcr Vogelschutz<\/a> \u00fcberwacht und zeigt f\u00fcr den Zeitraum seit 1990 ebenfalls einen deutlichen Anstieg. Vergleichen wir nun die beiden Statistiken, wird einwandfrei der <a href=\"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2011\/07\/babysstorch.jpg\">Zusammenhang zwischen St\u00f6rchen und Neugeburten<\/a> deutlich. Es ist also kein Mythos, sondern ein statisch belastbares Faktum, dass der Storch die Babys bringt, was im Volksmund auch l\u00e4ngst bekannt ist.<\/p>\n<p>Die Berliner und Br\u00fcsseler L\u00fcgenbande wird sich jedoch nat\u00fcrlich nicht einfach selbst verraten, sondern spielt s\u00e4mtliche ihrer noch verbliebenen M\u00f6glichkeiten bis zum Schluss aus. Der EU-Krug geht eben solange zum Geldbrunnen, bis er zerbricht. Vielleicht ergibt sich dies sogar schneller, als mancher zu hoffen wagt, denn die Fluglobby m\u00f6chte offenbar aus der CO2-Sekte aussteigen, wie die <a href=\"http:\/\/www.welt.de\/wirtschaft\/article13465253\/Airlines-wollen-die-EU-Klimavorschriften-kippen.html\">Welt<\/a> am 03.07.2011 berichtete:<\/p>\n<blockquote><p>Der Europ\u00e4ische Gerichtshof in Luxemburg er\u00f6ffnet ein Verfahren, in dem der Amerikanische Luftfahrtsverband eine Richtlinie Br\u00fcssels anficht. Das 2008 verabschiedete Gesetz sieht vor, dass ab Januar 2012 alle Fluggesellschaften, die in die Europ\u00e4ische Union fliegen oder dort starten, am Handel mit CO2-Zertifikaten teilnehmen m\u00fcssen.<\/p>\n<p>[&#8230;]<\/p>\n<p>Airbus-Chef Tom Enders warnte Klimakommissarin Connie Hedegaard j\u00fcngst in einem Brief, von so wichtigen Marktteilnehmern \u201eVergeltung zu riskieren, ist verr\u00fcckt\u201c.<\/p><\/blockquote>\n<p>Ob &#8222;CO2nny&#8220; Hedegaard ihre harte Linie mit der Luftbesteuerung wohl bis zum Ende durchziehen wird? Zuzutrauen ist der Baggage im vermeintlichen Zentrum der Macht in Br\u00fcssel wirklich alles, fernab jeder Realit\u00e4t, aber dieser hirnlose und gekaufte Haufen von M\u00f6chtegern-Diktatoren ist in Wahrheit eine Luftblase und wird einmal zerplatzen, wie jede L\u00fcge.<\/p>\n<p>Nicht hirnlos, sondern im Gegenteil absolut hirnverbrannt muss stattdessen das betitelt werden, was das Umweltbundesamt in Sachen &#8222;Klimarettung&#8220; zusammengetragen und im April 2011 ver\u00f6ffentlicht hat. In der knapp <a href=\"http:\/\/www.umweltdaten.de\/publikationen\/fpdf-l\/4125.pdf\">50-seitigen Brosch\u00fcre<\/a> mit dem Titel &#8222;Geo-Engineering &#8211; wirksamer Klimaschutz oder Gr\u00f6\u00dfenwahn?&#8220; werden die folgenden Ma\u00dfnahmen zur Rettung unseres Klimas allen Ernstes als mehr oder weniger brauchbare L\u00f6sungen vorgeschlagen:<\/p>\n<ul>\n<li>Wei\u00dfen von D\u00e4chern und Aufhellung von menschlichen Ansiedlungen.<\/li>\n<li>Reflektivere Feldfrucht- und Gr\u00fcnlandsorten.<\/li>\n<li>W\u00fcstenreflektoren: W\u00fcstengebiete mit reflektierenden Planen bedecken.<\/li>\n<li>R\u00fcckstrahlung des Sonnenlichtes durch helle, reflektierende Gegenst\u00e4nde (z. B. schwimmende Kissen) auf der Meeresoberfl\u00e4che.<\/li>\n<li>Eine k\u00fcnstliche Anreicherung der maritimen Atmosph\u00e4re mit Kondensationskernen k\u00f6nnte die Wolkenalbedo merklich erh\u00f6hen, weil sich dann erheblich mehr und kleinere Tr\u00f6pfchen bilden w\u00fcrden, die das Sonnenlicht st\u00e4rker streuen und zur\u00fcckwerfen w\u00fcrden.<\/li>\n<li>Ausbringung von Aluminiumschnipseln oder reflektierenden Kleinstballons oder von Chemikalien, vor allem von Schwefelverbindungen, in die Stratosph\u00e4re (17 &#8211; 50 km H\u00f6he).<\/li>\n<li>Beeinflussung des Strahlungshaushaltes durch Installationen im erdnahen Weltraum, wie z. B. spiegelnde Scheiben oder Saturn-\u00e4hnliche Ringe aus Staubpartikeln. Oder auch ein einzelner Riesenspiegel, ein ultrad\u00fcnnes Geflecht aus Aluminiumf\u00e4den oder Billionen reflektierender Scheiben zwischen Sonne und Erde.<\/li>\n<li>Abscheidung und Speicherung von Kohlendioxid (CCS).<\/li>\n<li>Kohlendioxidfilterung aus der Umgebungsluft.<\/li>\n<li>Kohlenstoff in Pflanzen speichern oder in Produkten, die aus den Pflanzen hergestellt wurden, zum Beispiel Bauholz.<\/li>\n<li>Direkte Speicherung von Biomasse: Pflanzenmaterial soll hierf\u00fcr entweder luftdicht verschlossen im Boden eingelagert oder im Meer versenkt werden.<\/li>\n<li>Aufforstung.<\/li>\n<li>Ozeand\u00fcngung.<\/li>\n<li>Ozeankalkung.<\/li>\n<li>Nutzung der Prozesse bei der Verwitterung (terrestrische und marine Methoden).<\/li>\n<\/ul>\n<p>Lesen Sie dieses Papier des Umweltbundesamtes besser nicht, falls Sie ein eher zart besaitetes Wahrheitsgem\u00fct besitzen, denn Sie k\u00f6nnten in Anbetracht des darin beschriebenen und tats\u00e4chlich real in Betracht gezogenen Irrsinns zum Klima-Amokl\u00e4ufer mutieren &#8211; und au\u00dferdem w\u00e4hrend Ihres Hyperventilierens \u00fcberdurchschnittlich viel des b\u00f6sen CO2 freisetzen.<\/p>\n<p>Bezahlen Sie eigentlich gerne Steuern in diesem Land? Nun, sehen Sie es einfach so: Sie spenden ein bisschen Geld &#8211; der gr\u00f6\u00dfte Teil wird schlie\u00dflich nach Griechenland und Co \u00fcberwiesen &#8211; f\u00fcr einen guten Zweck, denn stellen Sie sich vor, diese Leute im Umweltbundesamt w\u00fcrden frei herumlaufen, w\u00e4ren arbeitslos oder obdachlos. Was meinen Sie, wie gef\u00e4hrlich diese Bande in freier Wildbahn w\u00e4re?<\/p>\n<p>Insofern ist ihre staatlich bezahlte Betreuung eher praktisch und sch\u00fctzt uns vor diesen schwer hirnkranken Kreaturen. Doch wer wei\u00df, was geschieht, wenn demn\u00e4chst kein Geld mehr f\u00fcr diesen Wahnsinn \u00fcbrig sein und die Bev\u00f6lkerung das Spiel auch nicht mehr freiwillig mitspielen wird? Spannende Zeiten warten auf uns.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uns droht demn\u00e4chst der Klimakollaps und anschlie\u00dfend eine von politischen Extremismen und Instabilit\u00e4ten gepr\u00e4gte Welt. Damit sch\u00fcren prominente Politiker nach wie vor Panik in Sachen Klima-L\u00fcge. In Anbetracht des langsam beginnenden Klimafaschismus wirken die haarstr\u00e4ubenden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20900,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering | Wahrheiten.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering | Wahrheiten.org\" \/>\n<meta property=\"og:description\" content=\"Uns droht demn\u00e4chst der Klimakollaps und anschlie\u00dfend eine von politischen Extremismen und Instabilit\u00e4ten gepr\u00e4gte Welt. Damit sch\u00fcren prominente Politiker nach wie vor Panik in Sachen Klima-L\u00fcge. In Anbetracht des langsam beginnenden Klimafaschismus wirken die haarstr\u00e4ubenden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/\" \/>\n<meta property=\"og:site_name\" content=\"Wahrheiten.org\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-04T22:03:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-16T19:07:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2011\/07\/514984.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"294\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wahrheiten.org\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wahrheiten.org\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/\",\"name\":\"Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering | Wahrheiten.org\",\"isPartOf\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#website\"},\"datePublished\":\"2011-07-04T22:03:30+00:00\",\"dateModified\":\"2017-04-16T19:07:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.wahrheiten.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#website\",\"url\":\"https:\/\/www.wahrheiten.org\/blog\/\",\"name\":\"Wahrheiten.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wahrheiten.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1\",\"name\":\"Wahrheiten.org\",\"sameAs\":[\"http:\/\/www.wahrheiten.org\"],\"url\":\"https:\/\/www.wahrheiten.org\/blog\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering | Wahrheiten.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/","og_locale":"de_DE","og_type":"article","og_title":"Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering | Wahrheiten.org","og_description":"Uns droht demn\u00e4chst der Klimakollaps und anschlie\u00dfend eine von politischen Extremismen und Instabilit\u00e4ten gepr\u00e4gte Welt. Damit sch\u00fcren prominente Politiker nach wie vor Panik in Sachen Klima-L\u00fcge. In Anbetracht des langsam beginnenden Klimafaschismus wirken die haarstr\u00e4ubenden [&hellip;]","og_url":"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/","og_site_name":"Wahrheiten.org","article_published_time":"2011-07-04T22:03:30+00:00","article_modified_time":"2017-04-16T19:07:21+00:00","og_image":[{"width":"294","height":"400","url":"https:\/\/www.wahrheiten.org\/blog\/wp-content\/uploads\/2011\/07\/514984.jpg","type":"image\/jpeg"}],"author":"Wahrheiten.org","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Wahrheiten.org","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/","url":"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/","name":"Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering | Wahrheiten.org","isPartOf":{"@id":"https:\/\/www.wahrheiten.org\/blog\/#website"},"datePublished":"2011-07-04T22:03:30+00:00","dateModified":"2017-04-16T19:07:21+00:00","author":{"@id":"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1"},"breadcrumb":{"@id":"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wahrheiten.org\/blog\/2011\/07\/05\/verrueckte-klimasekte-eine-stabile-weltordnung-durch-geo-engineering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.wahrheiten.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Verr\u00fcckte Klimasekte: Eine stabile Weltordnung durch Geo-Engineering"}]},{"@type":"WebSite","@id":"https:\/\/www.wahrheiten.org\/blog\/#website","url":"https:\/\/www.wahrheiten.org\/blog\/","name":"Wahrheiten.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wahrheiten.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.wahrheiten.org\/blog\/#\/schema\/person\/5f67e752a12bd580f912851bce4359f1","name":"Wahrheiten.org","sameAs":["http:\/\/www.wahrheiten.org"],"url":"https:\/\/www.wahrheiten.org\/blog"}]}},"_links":{"self":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts\/20875"}],"collection":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/comments?post=20875"}],"version-history":[{"count":0,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/posts\/20875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/media\/20900"}],"wp:attachment":[{"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/media?parent=20875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/categories?post=20875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wahrheiten.org\/blog\/wp-json\/wp\/v2\/tags?post=20875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}